{"id":9046,"date":"2026-07-15T06:35:10","date_gmt":"2026-07-15T06:35:10","guid":{"rendered":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/"},"modified":"2026-07-15T06:35:10","modified_gmt":"2026-07-15T06:35:10","slug":"ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd","status":"publish","type":"post","link":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/","title":{"rendered":"Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD"},"content":{"rendered":"<p><em><strong>Ripple rejoint la Fondation x402 en tant que membre principal pour soutenir les paiements par agents d\u2019IA utilisant XRP et RLUSD sur le Ledger XRP et le web ouvert.<\/strong><\/em><\/p>\n<p><span style=\"font-weight: 400\">Ripple a rejoint la Fondation x402 en tant que membre principal apr\u00e8s l\u2019annonce du lancement op\u00e9rationnel par la Linux Foundation. Le groupe supervisera x402, un <\/span><a href=\"https:\/\/www.livebitcoinnews.com\/ripple-ctos-xrp-staking-idea-puts-irs-crypto-rules-to-the-test\/\"><span style=\"font-weight: 400\">standard de paiement<\/span><\/a><span style=\"font-weight: 400\"> ouvert pour les transactions sur le web.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Coinbase a contribu\u00e9 au protocole x402, qui int\u00e8gre les paiements dans les interactions HTTP normales sur le web. Il est con\u00e7u pour les agents d\u2019IA, les API et les applications qui ont besoin de paiement lors de l\u2019\u00e9change de donn\u00e9es.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ripple a d\u00e9clar\u00e9 prendre d\u00e9j\u00e0 en charge les paiements bas\u00e9s sur x402 sur le Ledger XRP. L\u2019entreprise a indiqu\u00e9 que les agents d\u2019IA peuvent effectuer des transactions en utilisant XRP et RLUSD d\u00e8s aujourd\u2019hui.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La fondation compte d\u00e9sormais 40 membres issus des secteurs de la finance, des paiements, du cloud et de la blockchain. Les membres principaux incluent Ripple, Coinbase, Circle, Visa, Mastercard, Stripe, AWS et Google.<\/span><\/p>\n<h2><b>Ripple apporte les outils du Ledger XRP \u00e0 x402<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Ripple a d\u00e9clar\u00e9 que les agents d\u2019IA ont besoin de paiements qui fonctionnent aussi rapidement que les donn\u00e9es circulent en ligne. Les agents d\u2019IA sont des syst\u00e8mes logiciels capables d\u2019accomplir des t\u00e2ches avec un apport humain limit\u00e9. Alors qu\u2019ils g\u00e8rent davantage d\u2019\u00e9tapes de transaction, les syst\u00e8mes de paiement ont besoin de normes plus claires.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Ripple is proud to join the x402 Foundation as a Premier Member.<\/p>\n<p>As AI agents begin to take on more of the transaction lifecycle, they&#39;ll need a way to pay that&#39;s as fast and reliable as the way they already exchange data. We&#39;ve been helping build that future on the XRP Ledger\u2026 <a href=\"https:\/\/t.co\/eSzTyXBQFm\">https:\/\/t.co\/eSzTyXBQFm<\/a><\/p>\n<p>&mdash; Ripple (@Ripple) <a href=\"https:\/\/x.com\/Ripple\/status\/2077017675247833365?ref_src=twsrc%5Etfw\">July 14, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span style=\"font-weight: 400\">Le Ledger XRP prend en charge les paiements, les transferts de jetons et les outils financiers connexes. Ripple a d\u00e9clar\u00e9 que le support de x402 permet aux agents d\u2019utiliser XRP et RLUSD pour les transactions. RLUSD est le <\/span><a href=\"https:\/\/www.livebitcoinnews.com\/ripple-ctos-xrp-staking-idea-puts-irs-crypto-rules-to-the-test\/\"><span style=\"font-weight: 400\">stablecoin de Ripple<\/span><\/a><span style=\"font-weight: 400\">, tandis que XRP est l\u2019actif natif du ledger.<\/span><\/p>\n<p><span style=\"font-weight: 400\">L\u2019entreprise a indiqu\u00e9 qu\u2019elle contribuera aux travaux techniques et de gouvernance. La gouvernance d\u00e9signe les r\u00e8gles et processus utilis\u00e9s pour guider un projet partag\u00e9. Ce r\u00f4le place Ripple au c\u0153ur des travaux sur les paiements natifs d\u2019Internet.<\/span><\/p>\n<h2><b>La Linux Foundation ouvre une gouvernance neutre vis-\u00e0-vis des fournisseurs<\/b><\/h2>\n<p><span style=\"font-weight: 400\">La <\/span><a href=\"https:\/\/www.linuxfoundation.org\/press\/linux-foundation-announces-operational-launch-of-x402-foundation-to-standardize-internet-native-payments-for-ai-agents-and-applications\"><span style=\"font-weight: 400\">Linux Foundation<\/span><\/a><span style=\"font-weight: 400\"> a annonc\u00e9 que la Fondation x402 est d\u00e9sormais active sous une gouvernance ouverte. Son r\u00f4le est de g\u00e9rer x402 en tant que standard de paiement partag\u00e9 sur HTTP. HTTP est le syst\u00e8me commun utilis\u00e9 par les sites web et les services en ligne pour \u00e9changer des donn\u00e9es.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le protocole ajoute des fonctionnalit\u00e9s de paiement s\u00e9curis\u00e9es directement dans les requ\u00eates et r\u00e9ponses web. Cela peut permettre \u00e0 une application de demander des donn\u00e9es et d\u2019effectuer un paiement en un seul flux. Le standard prend en charge des types de paiement tels que les cartes, les stablecoins et d\u2019autres options num\u00e9riques.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La fondation a indiqu\u00e9 que le mod\u00e8le vise \u00e0 \u00e9viter le verrouillage par un fournisseur. Le verrouillage par un fournisseur se produit lorsque les utilisateurs d\u00e9pendent trop d\u2019un seul fournisseur. La gouvernance ouverte donne aux membres les moyens de fa\u00e7onner les r\u00e8gles via des processus partag\u00e9s.<\/span><\/p>\n<p><b>Lire aussi : <\/b><a href=\"https:\/\/www.livebitcoinnews.com\/ripple-expands-rlusd-to-turkiye-as-stablecoin-hits-1-7b\/\"><b>Ripple \u00e9tend RLUSD \u00e0 la Turquie alors que le stablecoin atteint 1,7 milliard de dollars<\/b><\/a><\/p>\n<h2><b>Quarante membres soutiennent le standard de paiement pour l\u2019IA<\/b><\/h2>\n<p><span style=\"font-weight: 400\">La Fondation x402 a annonc\u00e9 que 40 organisations ont rejoint depuis le plan de lancement d\u2019avril.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Les membres principaux incluent Adyen, American Express, Cloudflare, Fiserv, Shopify, Stripe et Visa. La liste inclut \u00e9galement Circle, Coinbase, Google, Mastercard, Ripple, AWS et la <\/span><a href=\"https:\/\/www.livebitcoinnews.com\/ripple-clo-says-clarity-act-matters-despite-trump-veto-calls\/\"><span style=\"font-weight: 400\">Fondation Solana<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Les membres g\u00e9n\u00e9raux incluent Fireblocks, LayerZero Labs, NEAR Foundation, Polygon Labs, Quant Network et zerohash. Les membres associ\u00e9s incluent la Fondation Cardano, Casper, BSV Association et d\u2019autres groupes. La liste large montre l\u2019int\u00e9r\u00eat des entreprises de paiement, des \u00e9quipes blockchain et des fournisseurs de cloud.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Coinbase a d\u00e9clar\u00e9 que x402 a \u00e9t\u00e9 cr\u00e9\u00e9 parce que les agents d\u2019IA manquaient d\u2019une m\u00e9thode de paiement native.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le transfert du protocole \u00e0 la Linux Foundation le place sous une supervision industrielle plus large. Les d\u00e9veloppeurs peuvent d\u00e9sormais suivre l\u2019adoption dans les applications, les API, les portefeuilles et les syst\u00e8mes marchands.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ripple rejoint la Fondation x402 en tant que membre principal pour soutenir les paiements par agents d\u2019IA utilisant XRP et RLUSD sur le Ledger XRP et le web ouvert. Ripple a rejoint la Fondation x402 en tant que membre principal apr\u00e8s l\u2019annonce du lancement op\u00e9rationnel par la Linux Foundation. Le groupe supervisera x402, un standard [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-9046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ripple-news-xrp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD - France Live Bitcoin News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD - France Live Bitcoin News\" \/>\n<meta property=\"og:description\" content=\"Ripple rejoint la Fondation x402 en tant que membre principal pour soutenir les paiements par agents d\u2019IA utilisant XRP et RLUSD sur le Ledger XRP et le web ouvert. Ripple a rejoint la Fondation x402 en tant que membre principal apr\u00e8s l\u2019annonce du lancement op\u00e9rationnel par la Linux Foundation. Le groupe supervisera x402, un standard [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/\" \/>\n<meta property=\"og:site_name\" content=\"France Live Bitcoin News\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T06:35:10+00:00\" \/>\n<meta name=\"author\" content=\"frenchlbn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"frenchlbn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/\"},\"author\":{\"name\":\"frenchlbn\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/#\\\/schema\\\/person\\\/cf8f1f85189588768e507a2eb234cba8\"},\"headline\":\"Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD\",\"datePublished\":\"2026-07-15T06:35:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/\"},\"wordCount\":734,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/Ripples-XRPL-Enhances-Programmability-as-BlackRocks-BUIDL-Swap-Gains-Momentum.png\",\"articleSection\":[\"Ripple News - XRP\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/\",\"name\":\"Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD - France Live Bitcoin News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/Ripples-XRPL-Enhances-Programmability-as-BlackRocks-BUIDL-Swap-Gains-Momentum.png\",\"datePublished\":\"2026-07-15T06:35:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/#\\\/schema\\\/person\\\/cf8f1f85189588768e507a2eb234cba8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/Ripples-XRPL-Enhances-Programmability-as-BlackRocks-BUIDL-Swap-Gains-Momentum.png\",\"contentUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/Ripples-XRPL-Enhances-Programmability-as-BlackRocks-BUIDL-Swap-Gains-Momentum.png\",\"width\":1216,\"height\":832},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/\",\"name\":\"France Live Bitcoin News\",\"description\":\"Live Bitcoin News est la source d&#039;informations les plus r\u00e9centes sur Ethereum, XRP, DeFi, Web 3.0, les tendances crypto, l&#039;analyse de march\u00e9, la blockchain et les actualit\u00e9s financi\u00e8res mondiales, 24 heures sur 24 et 7 jours sur 7.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/#\\\/schema\\\/person\\\/cf8f1f85189588768e507a2eb234cba8\",\"name\":\"frenchlbn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g\",\"caption\":\"frenchlbn\"},\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/author\\\/frenchlbn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD - France Live Bitcoin News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/","og_locale":"fr_FR","og_type":"article","og_title":"Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD - France Live Bitcoin News","og_description":"Ripple rejoint la Fondation x402 en tant que membre principal pour soutenir les paiements par agents d\u2019IA utilisant XRP et RLUSD sur le Ledger XRP et le web ouvert. Ripple a rejoint la Fondation x402 en tant que membre principal apr\u00e8s l\u2019annonce du lancement op\u00e9rationnel par la Linux Foundation. Le groupe supervisera x402, un standard [&hellip;]","og_url":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/","og_site_name":"France Live Bitcoin News","article_published_time":"2026-07-15T06:35:10+00:00","author":"frenchlbn","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"frenchlbn","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/#article","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/"},"author":{"name":"frenchlbn","@id":"https:\/\/global.livebitcoinnews.com\/fr\/#\/schema\/person\/cf8f1f85189588768e507a2eb234cba8"},"headline":"Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD","datePublished":"2026-07-15T06:35:10+00:00","mainEntityOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/"},"wordCount":734,"commentCount":0,"image":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/fr\/wp-content\/uploads\/sites\/4\/2026\/07\/Ripples-XRPL-Enhances-Programmability-as-BlackRocks-BUIDL-Swap-Gains-Momentum.png","articleSection":["Ripple News - XRP"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/","url":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/","name":"Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD - France Live Bitcoin News","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/#primaryimage"},"image":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/fr\/wp-content\/uploads\/sites\/4\/2026\/07\/Ripples-XRPL-Enhances-Programmability-as-BlackRocks-BUIDL-Swap-Gains-Momentum.png","datePublished":"2026-07-15T06:35:10+00:00","author":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/#\/schema\/person\/cf8f1f85189588768e507a2eb234cba8"},"breadcrumb":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/#primaryimage","url":"https:\/\/global.livebitcoinnews.com\/fr\/wp-content\/uploads\/sites\/4\/2026\/07\/Ripples-XRPL-Enhances-Programmability-as-BlackRocks-BUIDL-Swap-Gains-Momentum.png","contentUrl":"https:\/\/global.livebitcoinnews.com\/fr\/wp-content\/uploads\/sites\/4\/2026\/07\/Ripples-XRPL-Enhances-Programmability-as-BlackRocks-BUIDL-Swap-Gains-Momentum.png","width":1216,"height":832},{"@type":"BreadcrumbList","@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/ripple-rejoint-la-fondation-x402-pour-faire-progresser-les-paiements-ia-avec-xrp-et-rlusd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/global.livebitcoinnews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Ripple rejoint la Fondation x402 pour faire progresser les paiements IA avec XRP et RLUSD"}]},{"@type":"WebSite","@id":"https:\/\/global.livebitcoinnews.com\/fr\/#website","url":"https:\/\/global.livebitcoinnews.com\/fr\/","name":"France Live Bitcoin News","description":"Live Bitcoin News est la source d&#039;informations les plus r\u00e9centes sur Ethereum, XRP, DeFi, Web 3.0, les tendances crypto, l&#039;analyse de march\u00e9, la blockchain et les actualit\u00e9s financi\u00e8res mondiales, 24 heures sur 24 et 7 jours sur 7.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/global.livebitcoinnews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/global.livebitcoinnews.com\/fr\/#\/schema\/person\/cf8f1f85189588768e507a2eb234cba8","name":"frenchlbn","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g","caption":"frenchlbn"},"url":"https:\/\/global.livebitcoinnews.com\/fr\/author\/frenchlbn\/"}]}},"_links":{"self":[{"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/posts\/9046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/comments?post=9046"}],"version-history":[{"count":0,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/posts\/9046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/media\/9045"}],"wp:attachment":[{"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/media?parent=9046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/categories?post=9046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/tags?post=9046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}