{"id":9135,"date":"2026-07-15T18:08:09","date_gmt":"2026-07-15T18:08:09","guid":{"rendered":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/"},"modified":"2026-07-15T18:08:09","modified_gmt":"2026-07-15T18:08:09","slug":"hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano","status":"publish","type":"post","link":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/","title":{"rendered":"Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano"},"content":{"rendered":"<ul>\n<li style=\"font-weight: 400\"><em><span style=\"font-weight: 400\">Hoskinson affirme que RealFi pourrait devenir une source majeure de Cardano TVL et de transactions.<\/span><\/em><\/li>\n<li style=\"font-weight: 400\"><em><span style=\"font-weight: 400\">Le testnet de phase 1 a attir\u00e9 plus de 1\u00a0000 utilisateurs et pr\u00e8s de 500 portefeuilles v\u00e9rifi\u00e9s.<\/span><\/em><\/li>\n<li style=\"font-weight: 400\"><em><span style=\"font-weight: 400\">RealFi cible la croissance de DeFi gr\u00e2ce au rendement, aux pi\u00e8ces stables et \u00e0 des cas d&rsquo;utilisation de pr\u00eats r\u00e9els.<\/span><\/em><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Le fondateur de Cardano, Charles Hoskinson, estime que l&rsquo;initiative RealFi du r\u00e9seau pourrait devenir un moteur majeur de l&rsquo;activit\u00e9 financi\u00e8re d\u00e9centralis\u00e9e en augmentant la valeur totale verrouill\u00e9e (TVL) et les transactions en cha\u00eene. Ses commentaires font suite \u00e0 une forte participation pr\u00e9coce lors du testnet de phase 1 du projet, alors que le protocole se rapproche d&rsquo;un futur lancement du r\u00e9seau principal.<\/span><\/p>\n<h2><b>RealFi pourrait stimuler la TVL et l&rsquo;activit\u00e9 r\u00e9seau de Cardano<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Charles Hoskinson a d\u00e9clar\u00e9 que RealFi avait le potentiel de devenir un contributeur majeur \u00e0 l\u2019\u00e9cosyst\u00e8me DeFi de Cardano. Selon<\/span><a href=\"https:\/\/x.com\/IOHK_Charles\/status\/2077192306155983019\"><span style=\"font-weight: 400\">remarques<\/span><\/a><span style=\"font-weight: 400\">Partag\u00e9 sur X, le protocole pourrait g\u00e9n\u00e9rer une TVL importante tout en augmentant le volume des transactions sur le r\u00e9seau.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Hoskinson a expliqu\u00e9 que les utilisateurs doivent d\u00e9poser des actifs dans des contrats intelligents RealFi avant d&rsquo;acc\u00e9der aux services financiers du protocole. Ces fonds restent bloqu\u00e9s tout en gagnant du rendement, cr\u00e9ant ainsi une source constante de liquidit\u00e9s au sein du r\u00e9seau.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Chaque d\u00e9p\u00f4t, retrait et distribution de rendement produit \u00e9galement des transactions en cha\u00eene. En cons\u00e9quence, une participation accrue des utilisateurs pourrait naturellement augmenter l\u2019activit\u00e9 du r\u00e9seau de Cardano au fil du temps.<\/span><\/p>\n<p><i><span style=\"font-weight: 400\">\u00ab\u00a0Ce qui est cool avec RealFi, c&rsquo;est que ce sera un gros g\u00e9n\u00e9rateur TVL et TX pour Cardano\u00a0\u00bb,<\/span><\/i><span style=\"font-weight: 400\">Hoskinson a d\u00e9clar\u00e9 en discutant de l\u2019impact \u00e0 long terme du protocole.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La structure bas\u00e9e sur le rendement peut \u00e9galement renforcer l\u2019infrastructure financi\u00e8re plus large de Cardano. De plus, les actifs verrouill\u00e9s pourraient prendre en charge l\u2019\u00e9mission de pi\u00e8ces stables et am\u00e9liorer la liquidit\u00e9 des applications d\u00e9centralis\u00e9es construites sur le r\u00e9seau.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">d\u00e9p\u00f4t pour une r\u00e9cup\u00e9ration de connaissances nulle<a href=\"https:\/\/t.co\/Z0RNF11Yls\">https:\/\/t.co\/Z0RNF11Yls<\/a><\/p>\n<p>\u2013 Charles Hoskinson (@IOHK_Charles)<a href=\"https:\/\/x.com\/IOHK_Charles\/status\/2077192306155983019?ref_src=twsrc%5Etfw\">15 juillet 2026<\/a><\/p>\n<\/blockquote>\n<p><a href=\"https:\/\/www.livebitcoinnews.com\/elon-musk-x-money-partners-with-ripple-linked-bank-as-realfi-expands-xrp-use\/\"><span style=\"font-weight: 400\">R\u00e9elFi<\/span><\/a><span style=\"font-weight: 400\">est con\u00e7u pour relier la finance d\u00e9centralis\u00e9e \u00e0 des services financiers pratiques. Le protocole vise \u00e0 prendre en charge des cas d&rsquo;utilisation tels que la microfinance et les pr\u00eats aux petites entreprises via des produits financiers bas\u00e9s sur la blockchain.<\/span><\/p>\n<h2><b>La croissance pr\u00e9coce de Testnet signale l\u2019int\u00e9r\u00eat de la communaut\u00e9<\/b><\/h2>\n<p><span style=\"font-weight: 400\">L\u2019\u00e9quipe RealFi a d\u00e9j\u00e0 signal\u00e9 une participation encourageante lors de la saison pionni\u00e8re du projet. En outre, plus de 1\u00a0000 utilisateurs ont rejoint le testnet de phase 1, tandis que pr\u00e8s de 500 portefeuilles v\u00e9rifi\u00e9s ont particip\u00e9 activement au d\u00e9ploiement initial.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Le projet a \u00e9galement attir\u00e9 plus de 2\u00a0000 abonn\u00e9s sur X, parall\u00e8lement \u00e0 un engagement communautaire croissant sur Discord. Bien que les chiffres repr\u00e9sentent une premi\u00e8re phase de test, ils sugg\u00e8rent un int\u00e9r\u00eat croissant pour le d\u00e9veloppement de RealFi.<\/span><\/p>\n<p><span style=\"font-weight: 400\">L&rsquo;\u00e9quipe a d\u00e9clar\u00e9 que l&rsquo;initiative se concentre sur la cr\u00e9ation d&rsquo;un stablecoin transparent soutenu par des actifs du monde r\u00e9el.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Par cons\u00e9quent, le protocole cherche \u00e0 relier la finance d\u00e9centralis\u00e9e \u00e0 l\u2019activit\u00e9 \u00e9conomique r\u00e9elle plut\u00f4t que de servir uniquement le commerce sp\u00e9culatif.<\/span><\/p>\n<p><a href=\"https:\/\/www.livebitcoinnews.com\/cardano-defi-tvl-cant-break-the-1b-wall\/\"><span style=\"font-weight: 400\">Cardano<\/span><\/a><span style=\"font-weight: 400\">La TVL de s&rsquo;\u00e9l\u00e8ve actuellement \u00e0 environ 71,56 millions de dollars, ce qui reste bien en dessous des 41,09 milliards de dollars d&rsquo;Ethereum et des 4,91 milliards de dollars de Solana.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">N\u00e9anmoins, Hoskinson pense que RealFi pourrait aider \u00e0 r\u00e9duire cet \u00e9cart en attirant des capitaux suppl\u00e9mentaires et en g\u00e9n\u00e9rant une activit\u00e9 soutenue en cha\u00eene \u00e0 mesure que le d\u00e9veloppement progresse vers le r\u00e9seau principal.<\/span><\/p>\n<p><!-- source_url: https:\/\/www.livebitcoinnews.com\/hoskinson-says-realfi-could-become-cardanos-next-major-growth-engine\/ --><\/p>\n<p><em>Source : <a href=\"https:\/\/www.livebitcoinnews.com\/hoskinson-says-realfi-could-become-cardanos-next-major-growth-engine\/\" rel=\"nofollow noopener\" target=\"_blank\">Live Bitcoin News<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoskinson affirme que RealFi pourrait devenir une source majeure de Cardano TVL et de transactions. Le testnet de phase 1 a attir\u00e9 plus de 1\u00a0000 utilisateurs et pr\u00e8s de 500 portefeuilles v\u00e9rifi\u00e9s. RealFi cible la croissance de DeFi gr\u00e2ce au rendement, aux pi\u00e8ces stables et \u00e0 des cas d&rsquo;utilisation de pr\u00eats r\u00e9els. Le fondateur de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[36],"tags":[182,535,46,1375],"class_list":["post-9135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-defi","tag-cardano","tag-charles-hoskinson","tag-defi","tag-realfi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano - France Live Bitcoin News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano - France Live Bitcoin News\" \/>\n<meta property=\"og:description\" content=\"Hoskinson affirme que RealFi pourrait devenir une source majeure de Cardano TVL et de transactions. Le testnet de phase 1 a attir\u00e9 plus de 1\u00a0000 utilisateurs et pr\u00e8s de 500 portefeuilles v\u00e9rifi\u00e9s. RealFi cible la croissance de DeFi gr\u00e2ce au rendement, aux pi\u00e8ces stables et \u00e0 des cas d&rsquo;utilisation de pr\u00eats r\u00e9els. Le fondateur de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/\" \/>\n<meta property=\"og:site_name\" content=\"France Live Bitcoin News\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T18:08:09+00:00\" \/>\n<meta name=\"author\" content=\"frenchlbn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"frenchlbn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/\"},\"author\":{\"name\":\"frenchlbn\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/#\\\/schema\\\/person\\\/cf8f1f85189588768e507a2eb234cba8\"},\"headline\":\"Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano\",\"datePublished\":\"2026-07-15T18:08:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/\"},\"wordCount\":668,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/Cardanos_Charles_Hoskinson_Favors_Sui_Blockchain_Over_Solana_01-600x333-1-200x200-2-1-1.webp\",\"keywords\":[\"Cardano\",\"Charles Hoskinson\",\"DeFi\",\"RealFi\"],\"articleSection\":[\"DeFi\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/\",\"name\":\"Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano - France Live Bitcoin News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/Cardanos_Charles_Hoskinson_Favors_Sui_Blockchain_Over_Solana_01-600x333-1-200x200-2-1-1.webp\",\"datePublished\":\"2026-07-15T18:08:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/#\\\/schema\\\/person\\\/cf8f1f85189588768e507a2eb234cba8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/Cardanos_Charles_Hoskinson_Favors_Sui_Blockchain_Over_Solana_01-600x333-1-200x200-2-1-1.webp\",\"contentUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2026\\\/07\\\/Cardanos_Charles_Hoskinson_Favors_Sui_Blockchain_Over_Solana_01-600x333-1-200x200-2-1-1.webp\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/2026\\\/07\\\/15\\\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/\",\"name\":\"France Live Bitcoin News\",\"description\":\"Live Bitcoin News est la source d&#039;informations les plus r\u00e9centes sur Ethereum, XRP, DeFi, Web 3.0, les tendances crypto, l&#039;analyse de march\u00e9, la blockchain et les actualit\u00e9s financi\u00e8res mondiales, 24 heures sur 24 et 7 jours sur 7.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/#\\\/schema\\\/person\\\/cf8f1f85189588768e507a2eb234cba8\",\"name\":\"frenchlbn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g\",\"caption\":\"frenchlbn\"},\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/fr\\\/author\\\/frenchlbn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano - France Live Bitcoin News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/","og_locale":"fr_FR","og_type":"article","og_title":"Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano - France Live Bitcoin News","og_description":"Hoskinson affirme que RealFi pourrait devenir une source majeure de Cardano TVL et de transactions. Le testnet de phase 1 a attir\u00e9 plus de 1\u00a0000 utilisateurs et pr\u00e8s de 500 portefeuilles v\u00e9rifi\u00e9s. RealFi cible la croissance de DeFi gr\u00e2ce au rendement, aux pi\u00e8ces stables et \u00e0 des cas d&rsquo;utilisation de pr\u00eats r\u00e9els. Le fondateur de [&hellip;]","og_url":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/","og_site_name":"France Live Bitcoin News","article_published_time":"2026-07-15T18:08:09+00:00","author":"frenchlbn","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"frenchlbn","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/#article","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/"},"author":{"name":"frenchlbn","@id":"https:\/\/global.livebitcoinnews.com\/fr\/#\/schema\/person\/cf8f1f85189588768e507a2eb234cba8"},"headline":"Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano","datePublished":"2026-07-15T18:08:09+00:00","mainEntityOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/"},"wordCount":668,"commentCount":0,"image":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/fr\/wp-content\/uploads\/sites\/4\/2026\/07\/Cardanos_Charles_Hoskinson_Favors_Sui_Blockchain_Over_Solana_01-600x333-1-200x200-2-1-1.webp","keywords":["Cardano","Charles Hoskinson","DeFi","RealFi"],"articleSection":["DeFi"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/","url":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/","name":"Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano - France Live Bitcoin News","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/#primaryimage"},"image":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/fr\/wp-content\/uploads\/sites\/4\/2026\/07\/Cardanos_Charles_Hoskinson_Favors_Sui_Blockchain_Over_Solana_01-600x333-1-200x200-2-1-1.webp","datePublished":"2026-07-15T18:08:09+00:00","author":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/#\/schema\/person\/cf8f1f85189588768e507a2eb234cba8"},"breadcrumb":{"@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/#primaryimage","url":"https:\/\/global.livebitcoinnews.com\/fr\/wp-content\/uploads\/sites\/4\/2026\/07\/Cardanos_Charles_Hoskinson_Favors_Sui_Blockchain_Over_Solana_01-600x333-1-200x200-2-1-1.webp","contentUrl":"https:\/\/global.livebitcoinnews.com\/fr\/wp-content\/uploads\/sites\/4\/2026\/07\/Cardanos_Charles_Hoskinson_Favors_Sui_Blockchain_Over_Solana_01-600x333-1-200x200-2-1-1.webp","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/global.livebitcoinnews.com\/fr\/2026\/07\/15\/hoskinson-dit-que-realfi-pourrait-devenir-le-prochain-moteur-de-croissance-majeur-de-cardano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/global.livebitcoinnews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Hoskinson dit que RealFi pourrait devenir le prochain moteur de croissance majeur de Cardano"}]},{"@type":"WebSite","@id":"https:\/\/global.livebitcoinnews.com\/fr\/#website","url":"https:\/\/global.livebitcoinnews.com\/fr\/","name":"France Live Bitcoin News","description":"Live Bitcoin News est la source d&#039;informations les plus r\u00e9centes sur Ethereum, XRP, DeFi, Web 3.0, les tendances crypto, l&#039;analyse de march\u00e9, la blockchain et les actualit\u00e9s financi\u00e8res mondiales, 24 heures sur 24 et 7 jours sur 7.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/global.livebitcoinnews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/global.livebitcoinnews.com\/fr\/#\/schema\/person\/cf8f1f85189588768e507a2eb234cba8","name":"frenchlbn","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5aab91d9763557995200945b725c0540d609d4ae23c1588dd2fc1aa80a096cde?s=96&d=mm&r=g","caption":"frenchlbn"},"url":"https:\/\/global.livebitcoinnews.com\/fr\/author\/frenchlbn\/"}]}},"_links":{"self":[{"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/posts\/9135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/comments?post=9135"}],"version-history":[{"count":0,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/posts\/9135\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/media\/9134"}],"wp:attachment":[{"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/media?parent=9135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/categories?post=9135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/fr\/wp-json\/wp\/v2\/tags?post=9135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}