{"id":8969,"date":"2026-07-13T22:01:07","date_gmt":"2026-07-13T22:01:07","guid":{"rendered":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/"},"modified":"2026-07-13T22:01:07","modified_gmt":"2026-07-13T22:01:07","slug":"jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor","status":"publish","type":"post","link":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/","title":{"rendered":"Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor"},"content":{"rendered":"<p><em><strong>Jito schl\u00e4gt JIP-38 vor, seinen 80-prozentigen Anteil an den JTX-Geb\u00fchren f\u00fcr mindestens ein Jahr f\u00fcr automatisierte JTO-R\u00fcckk\u00e4ufe und -Verbrennungen zu verwenden.<\/strong><\/em><\/p>\n<p><span style=\"font-weight: 400\">Jito hat JIP-38 gestartet, einen Vorschlag, JTX-Geb\u00fchreneinnahmen in JTO-R\u00fcckk\u00e4ufe und -Verbrennungen umzuleiten. Der Plan w\u00fcrde mindestens ein Jahr nach der Inbetriebnahme von JTX gelten.<\/span><\/p>\n<p><span style=\"font-weight: 400\">SolanaFloor berichtete, dass der Vorschlag den gesamten 80-prozentigen Anteil des DAO an den JTX-Geb\u00fchren abdeckt. Diese Einnahmen w\u00fcrden automatisierte und dauerhafte JTO-K\u00e4ufe unterst\u00fctzen<\/span><a href=\"https:\/\/www.livebitcoinnews.com\/solana-rwa-boom-hits-3-03b-as-transfer-volume-jumps-120-5-in-just-one-month\/\"><span style=\"font-weight: 400\">Token brennt<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Jito sagte, dass der Vorschlag das Netzwerk offiziell als Token-fokussiert festlegt. Der Plan stellt JTO in den Mittelpunkt der zuk\u00fcnftigen Einnahmenverwendung und DAO-Kontrolle.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Der Vorschlag ist zu einem wichtigen Thema im gesamten Solana-\u00d6kosystem geworden. H\u00e4ndler beobachten nun, wie das DAO mit der Abstimmung und dem Startzeitplan umgeht.<\/span><\/p>\n<h2><b>JIP-38 stellt JTO in den Mittelpunkt der Geb\u00fchren<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Jito sagte, dass JIP-38 jetzt live ist und einen auf Token ausgerichteten Umsatzplan festlegt. Der Vorschlag umfasst Einnahmen aus JTX, dem geplanten \u00d6kosystem<\/span><a href=\"https:\/\/www.livebitcoinnews.com\/solana-bulls-eye-range-high-after-281m-shorts-trigger-fast-sol-recovery-move\/\"><span style=\"font-weight: 400\">Handelsprodukt<\/span><\/a><span style=\"font-weight: 400\">. Im Rahmen des Plans w\u00fcrde Jito DAO seinen JTX-Umsatzanteil f\u00fcr JTO verwenden.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">JIP-38 ist jetzt live.<\/p>\n<p>Der Wert sollte mit dem Netzwerk leben. Mit diesem Vorschlag wird Jito offiziell als Token-zentriertes Netzwerk etabliert, das 100 % des Umsatzanteils des Jito DAO \u00fcbernimmt<a href=\"https:\/\/x.com\/jtx_trade?ref_src=twsrc%5Etfw\">@JTX_trade<\/a>zu programmatischen R\u00fcckk\u00e4ufen und Verbrennungen von<a href=\"https:\/\/x.com\/search?q=%24JTO&amp;src=ctag&amp;ref_src=twsrc%5Etfw\">$JTO<\/a>f\u00fcr mindestens 1 Jahr ab JTX-Start.<\/p>\n<p>\u2013 Jito (@jito_sol)<a href=\"https:\/\/x.com\/jito_sol\/status\/2076672253568192707?ref_src=twsrc%5Etfw\">13. Juli 2026<\/a><\/p>\n<\/blockquote>\n<p><a href=\"https:\/\/x.com\/SolanaFloor\/status\/2076676044535583149?s=20\"><span style=\"font-weight: 400\">SolanaFloor berichtete<\/span><\/a><span style=\"font-weight: 400\">dass der volle 80-prozentige Anteil von Jito DAO an den JTX-Geb\u00fchren den Plan finanzieren w\u00fcrde. Dieser volle Anteil w\u00fcrde automatisierte JTO-K\u00e4ufe und Token-Verbrennungen unterst\u00fctzen. Das Modell w\u00fcrde nach der Einf\u00fchrung von JTX mindestens ein Jahr lang laufen.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Bei einem R\u00fcckkauf werden Einnahmen verwendet, um Token vom Markt zu kaufen. Durch eine Verbrennung werden ausgew\u00e4hlte Token dann dauerhaft aus dem Vorrat entfernt. Diese Struktur verkn\u00fcpft die JTX-Aktivit\u00e4t mit JTO-Angebots\u00e4nderungen.<\/span><\/p>\n<h2><b>JTX-Umsatzroute zieht DAO-Fokus auf sich<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Nick Almond sagte, JIP-38 reduziere Bedenken hinsichtlich einer Wertverlagerung von JTO. Er sagte, alle DAO-Einnahmen von JTX w\u00fcrden in R\u00fcckk\u00e4ufe und Verbrennungen flie\u00dfen. Er beschrieb den Plan auch als einfache wirtschaftliche Grundlinie.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Eine gro\u00dfe Woche f\u00fcr Jito. Beginnend mit JIP-38, das Jito als tokenzentriertes Netzwerk festigt.<\/p>\n<p>Das hei\u00dft, es sollte keine Bedenken bestehen, dass der Wert im gesamten Jito-Netzwerk dem Eigenkapital und nicht dem Token zuflie\u00dft. Das bedeutet, dass alle Einnahmen, die das DAO von JTX erh\u00e4lt,\u2026<a href=\"https:\/\/t.co\/kfxCbVyyU1\">https:\/\/t.co\/kfxCbVyyU1<\/a><\/p>\n<p>\u2013 Nick Almond (@DrNickA)<a href=\"https:\/\/x.com\/DrNickA\/status\/2076673079749525720?ref_src=twsrc%5Etfw\">13. Juli 2026<\/a><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400\">Es wird erwartet, dass JTX Geb\u00fchren f\u00fcr Verm\u00f6genswerte im gesamten Solana-Netzwerk einzieht. Gem\u00e4\u00df JIP-38 w\u00fcrden diese Verm\u00f6genswerte zum Kauf von JTO verwendet. Die gekauften Token w\u00fcrden dann aus dem Vorrat genommen.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Der Vorschlag gibt der DAO auch die Kontrolle \u00fcber zuk\u00fcnftige Einnahmeentscheidungen. DAO-Mitglieder k\u00f6nnen dar\u00fcber abstimmen, wie mit den Einnahmen nach dem ersten Jahr umgegangen wird. Dies gibt der Governance eine direkte Rolle im Wirtschaftsdesign von Jito.<\/span><\/p>\n<p><b>Lesen Sie auch:<\/b><a href=\"https:\/\/www.livebitcoinnews.com\/solana-could-surge-to-127-if-it-clears-this-critical-resistance-analysis\/\"><b>Solana k\u00f6nnte auf 127 US-Dollar steigen, wenn es diesen kritischen Widerstand \u00fcberwindet: Analyse<\/b><\/a><\/p>\n<h2><b>Jito-Umsatzlinien werden auf ganz Solana ausgeweitet<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Das breitere Netzwerk von Jito umfasst JitoSOL, BAM und JTX. Jedes Produkt erf\u00fcllt eine andere Rolle im Inneren<\/span><a href=\"https:\/\/www.livebitcoinnews.com\/solana-breaks-year-long-btc-downtrend-as-bulls-target-100-soon\/\"><span style=\"font-weight: 400\">Solana-\u00d6kosystem<\/span><\/a><span style=\"font-weight: 400\">. Zusammen schaffen sie mehrere m\u00f6gliche Einnahmequellen f\u00fcr das DAO.<\/span><\/p>\n<p><span style=\"font-weight: 400\">JitoSOL ist der Liquid-Stake-Token des Projekts f\u00fcr SOL. Nick Almond sagte, dass Coinbase es als Hauptl\u00f6sung f\u00fcr SOL-Absteckungen nutzt. Er sagte auch, dass JitoSOL weltweit in ETNs und ETFs einsteige.<\/span><\/p>\n<p><span style=\"font-weight: 400\">BAM konzentriert sich auf die Verbesserung der Ausf\u00fchrungsumgebung und Handelsstruktur von Solana. JTX ist als Handelsoberfl\u00e4che f\u00fcr Solana-Nutzer geplant. Unter JIP-38 w\u00fcrden JTX-Geb\u00fchren zur\u00fcck in JTO flie\u00dfen.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Der n\u00e4chste Schwerpunkt liegt auf dem DAO-Prozess und dem endg\u00fcltigen Timing f\u00fcr JTX. Marktbeobachter k\u00f6nnen die H\u00f6he der Geb\u00fchren auch nach der Einf\u00fchrung verfolgen. Brennaufzeichnungen zeigen, wie viel JTO im Laufe der Zeit entfernt wird.<\/span><\/p>\n<p><!-- source_url: https:\/\/www.livebitcoinnews.com\/jito-proposes-massive-jto-buyback-and-burn-using-80-of-jtx-fees\/ --><\/p>\n<p><em>Quelle: <a href=\"https:\/\/www.livebitcoinnews.com\/jito-proposes-massive-jto-buyback-and-burn-using-80-of-jtx-fees\/\" rel=\"nofollow noopener\" target=\"_blank\">Live Bitcoin News<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jito schl\u00e4gt JIP-38 vor, seinen 80-prozentigen Anteil an den JTX-Geb\u00fchren f\u00fcr mindestens ein Jahr f\u00fcr automatisierte JTO-R\u00fcckk\u00e4ufe und -Verbrennungen zu verwenden. Jito hat JIP-38 gestartet, einen Vorschlag, JTX-Geb\u00fchreneinnahmen in JTO-R\u00fcckk\u00e4ufe und -Verbrennungen umzuleiten. Der Plan w\u00fcrde mindestens ein Jahr nach der Inbetriebnahme von JTX gelten. SolanaFloor berichtete, dass der Vorschlag den gesamten 80-prozentigen Anteil des [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-8969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-market-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor - German Live Bitcoin News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor - German Live Bitcoin News\" \/>\n<meta property=\"og:description\" content=\"Jito schl\u00e4gt JIP-38 vor, seinen 80-prozentigen Anteil an den JTX-Geb\u00fchren f\u00fcr mindestens ein Jahr f\u00fcr automatisierte JTO-R\u00fcckk\u00e4ufe und -Verbrennungen zu verwenden. Jito hat JIP-38 gestartet, einen Vorschlag, JTX-Geb\u00fchreneinnahmen in JTO-R\u00fcckk\u00e4ufe und -Verbrennungen umzuleiten. Der Plan w\u00fcrde mindestens ein Jahr nach der Inbetriebnahme von JTX gelten. SolanaFloor berichtete, dass der Vorschlag den gesamten 80-prozentigen Anteil des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/\" \/>\n<meta property=\"og:site_name\" content=\"German Live Bitcoin News\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-13T22:01:07+00:00\" \/>\n<meta name=\"author\" content=\"germanlbn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"germanlbn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/\"},\"author\":{\"name\":\"germanlbn\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\"},\"headline\":\"Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor\",\"datePublished\":\"2026-07-13T22:01:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/\"},\"wordCount\":665,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Jitos-BAM-upgrade-set-to-make-Solana-apps-richer-1.png\",\"articleSection\":[\"Market News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/\",\"name\":\"Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor - German Live Bitcoin News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Jitos-BAM-upgrade-set-to-make-Solana-apps-richer-1.png\",\"datePublished\":\"2026-07-13T22:01:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Jitos-BAM-upgrade-set-to-make-Solana-apps-richer-1.png\",\"contentUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Jitos-BAM-upgrade-set-to-make-Solana-apps-richer-1.png\",\"width\":1408,\"height\":704},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/13\\\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#website\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/\",\"name\":\"German Live Bitcoin News\",\"description\":\"Live Bitcoin News ist die Quelle f\u00fcr aktuelle Nachrichten zu Ethereum, XRP, DeFi, Web 3.0, Kryptotrends, Marktanalysen, Blockchain und globalen Finanznachrichten \u2013 24 Stunden am Tag, 7 Tage die Woche.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\",\"name\":\"germanlbn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"caption\":\"germanlbn\"},\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/author\\\/germanlbn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor - German Live Bitcoin News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/","og_locale":"de_DE","og_type":"article","og_title":"Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor - German Live Bitcoin News","og_description":"Jito schl\u00e4gt JIP-38 vor, seinen 80-prozentigen Anteil an den JTX-Geb\u00fchren f\u00fcr mindestens ein Jahr f\u00fcr automatisierte JTO-R\u00fcckk\u00e4ufe und -Verbrennungen zu verwenden. Jito hat JIP-38 gestartet, einen Vorschlag, JTX-Geb\u00fchreneinnahmen in JTO-R\u00fcckk\u00e4ufe und -Verbrennungen umzuleiten. Der Plan w\u00fcrde mindestens ein Jahr nach der Inbetriebnahme von JTX gelten. SolanaFloor berichtete, dass der Vorschlag den gesamten 80-prozentigen Anteil des [&hellip;]","og_url":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/","og_site_name":"German Live Bitcoin News","article_published_time":"2026-07-13T22:01:07+00:00","author":"germanlbn","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"germanlbn","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/#article","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/"},"author":{"name":"germanlbn","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a"},"headline":"Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor","datePublished":"2026-07-13T22:01:07+00:00","mainEntityOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/"},"wordCount":665,"commentCount":0,"image":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/Jitos-BAM-upgrade-set-to-make-Solana-apps-richer-1.png","articleSection":["Market News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/","url":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/","name":"Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor - German Live Bitcoin News","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/#website"},"primaryImageOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/#primaryimage"},"image":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/Jitos-BAM-upgrade-set-to-make-Solana-apps-richer-1.png","datePublished":"2026-07-13T22:01:07+00:00","author":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a"},"breadcrumb":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/#primaryimage","url":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/Jitos-BAM-upgrade-set-to-make-Solana-apps-richer-1.png","contentUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/Jitos-BAM-upgrade-set-to-make-Solana-apps-richer-1.png","width":1408,"height":704},{"@type":"BreadcrumbList","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/13\/jito-schlaegt-massiven-jto-rueckkauf-und-verbrennung-mit-80-prozent-der-jtx-gebuehren-vor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/global.livebitcoinnews.com\/ge\/"},{"@type":"ListItem","position":2,"name":"Jito schl\u00e4gt massiven JTO-R\u00fcckkauf und -Verbrennung mit 80 % der JTX-Geb\u00fchren vor"}]},{"@type":"WebSite","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#website","url":"https:\/\/global.livebitcoinnews.com\/ge\/","name":"German Live Bitcoin News","description":"Live Bitcoin News ist die Quelle f\u00fcr aktuelle Nachrichten zu Ethereum, XRP, DeFi, Web 3.0, Kryptotrends, Marktanalysen, Blockchain und globalen Finanznachrichten \u2013 24 Stunden am Tag, 7 Tage die Woche.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/global.livebitcoinnews.com\/ge\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a","name":"germanlbn","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","caption":"germanlbn"},"url":"https:\/\/global.livebitcoinnews.com\/ge\/author\/germanlbn\/"}]}},"_links":{"self":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts\/8969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/comments?post=8969"}],"version-history":[{"count":0,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts\/8969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/media\/8968"}],"wp:attachment":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/media?parent=8969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/categories?post=8969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/tags?post=8969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}