{"id":8999,"date":"2026-07-14T12:01:12","date_gmt":"2026-07-14T12:01:12","guid":{"rendered":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/"},"modified":"2026-07-14T12:01:12","modified_gmt":"2026-07-14T12:01:12","slug":"cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst","status":"publish","type":"post","link":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/","title":{"rendered":"Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft"},"content":{"rendered":"<p><strong><em>Cardano-Wallets mit 100.000 bis 100 Mio. ADA-Top-25,6-Milliarden-M\u00fcnzen, der h\u00f6chste Wert seit Februar 2023, da Sub-100-ADA-Wallets um 0,7 % fielen.<\/em><\/strong><\/p>\n<p><span style=\"font-weight: 400\">Die gr\u00f6\u00dferen Inhaber von Cardano haben ihren Betrag erh\u00f6ht<\/span><a href=\"https:\/\/www.livebitcoinnews.com\/cardano-v11-hard-fork-advances-as-discord-clash-fuels-governance-fears\/\"><span style=\"font-weight: 400\">ADA-Guthaben<\/span><\/a><span style=\"font-weight: 400\">auf ein 3,5-Jahres-Hoch. Der Schritt erfolgt, da Einzelhandels-Wallets das Risiko verringern.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Santiment Intelligence sagte, dass Wallets mit 100.000 bis 100 Millionen ADA mittlerweile mehr als 25,6 Milliarden M\u00fcnzen enthalten. Das ist ihr h\u00f6chster Stand seit Februar 2023.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Kleinere Geldb\u00f6rsen bewegen sich in die entgegengesetzte Richtung. Wallets mit weniger als 100 ADA enthalten etwa 0,7 % weniger Coins als vor vier Monaten.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die Aufteilung erfolgt, w\u00e4hrend ADA nach einer schwachen Preisentwicklung im Jahr 2026 nahe Mehrjahrestiefs handelt. Cardano zeigt auch weiterhin Aktivit\u00e4t in den Bereichen Entwicklung und Governance.<\/span><\/p>\n<h2><b>Gro\u00dfe ADA-Geldb\u00f6rsen erh\u00f6hen weiterhin das Angebot<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Santiment Intelligence meldete einen deutlichen Anstieg der wichtigsten Stakeholder-Beteiligungen von Cardano. Diese Wallets enthalten mittlerweile mehr als 25,6 Milliarden ADA. Zur Gruppe geh\u00f6ren Wallets mit 100.000 bis 100 Millionen ADA.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\u270d\ufe0f TL;DR: Die Beteiligungen der wichtigsten Stakeholder von Cardano erreichen ein 3,5-Jahres-Hoch<br \/>\ud83d\udcca Verwendete Metriken: Angebotsverteilung<br \/>\ud83d\udd17 Live-Chart:<a href=\"https:\/\/t.co\/9lzM6kxdcb\">https:\/\/t.co\/9lzM6kxdcb<\/a><\/p>\n<p>\ud83e\udd88 Cardanos 100.000 bis 100 Millionen ADA-Wallets enthalten jetzt mehr als 25,6 Milliarden M\u00fcnzen, den h\u00f6chsten Stand seit Februar 2023.<\/p>\n<p>\ud83d\udcc9 Der Einzelhandel \u00fcbernimmt die\u2026<a href=\"https:\/\/t.co\/7iHLl5xyHT\">pic.twitter.com\/7iHLl5xyHT<\/a><\/p>\n<p>\u2014 Santiment Intelligence (@SantimentData)<a href=\"https:\/\/x.com\/SantimentData\/status\/2076812863750992379?ref_src=twsrc%5Etfw\">13. Juli 2026<\/a><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400\">Nach Angaben des Unternehmens ist dieser Wert der h\u00f6chste seit Februar 2023. Whale- und Shark-Wallets werden oft auf gr\u00f6\u00dferes Marktverhalten beobachtet. Ihre Best\u00e4nde k\u00f6nnen zeigen, ob gr\u00f6\u00dfere Teilnehmer ihr Engagement erh\u00f6hen oder verringern.<\/span><\/p>\n<p><span style=\"font-weight: 400\">H\u00f6here Walsalden garantieren jedoch keinen sofortigen Erfolg<\/span><a href=\"https:\/\/www.livebitcoinnews.com\/cardanos-biggest-interoperability-push-now-brings-800-tokens-across-chains\/\"><span style=\"font-weight: 400\">ADA-Erholung<\/span><\/a><span style=\"font-weight: 400\">. Die Daten zeigen lediglich eine Ver\u00e4nderung der Angebotsverteilung. H\u00e4ndler ben\u00f6tigen m\u00f6glicherweise noch eine Preisbest\u00e4tigung, bevor sie mit einer st\u00e4rkeren Bewegung rechnen k\u00f6nnen.<\/span><\/p>\n<h2><b>Einzelhandelsgeldb\u00f6rsen reduzieren ADA-Guthaben<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Bei Einzelhandelsgeldb\u00f6rsen zeigt sich im gleichen Zeitraum ein anderes Muster. Santiment Intelligence sagte, dass ADA-Wallets unter 100 weniger M\u00fcnzen enthalten als vor vier Monaten. Ihre Gesamtbest\u00e4nde sind um etwa 0,7 % gesunken.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Dies deutet darauf hin, dass kleinere Inhaber w\u00e4hrend der Preisschw\u00e4che ihr Engagement reduziert haben. Die Preisentwicklung von ADA im Jahr 2026 steht weiterhin unter Druck. Der Verm\u00f6genswert wurde in den letzten Sitzungen auch nahe Mehrjahrestiefs gehandelt.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die Kluft zwischen gr\u00f6\u00dferen Geldb\u00f6rsen und Einzelhandels-Geldb\u00f6rsen ist zu einem wichtigen Marktsignal geworden. Gr\u00f6\u00dfere Geldb\u00f6rsen absorbieren mehr ADA, w\u00e4hrend kleinere Geldb\u00f6rsen die Geduld verlieren. Dennoch h\u00e4ngt die Marktreaktion von der Nachfrage, dem Volumen und den allgemeinen Kryptobedingungen ab.<\/span><\/p>\n<p><b>Lesen Sie auch:<\/b><a href=\"https:\/\/www.livebitcoinnews.com\/cardano-v11-hard-fork-advances-as-discord-clash-fuels-governance-fears\/\"><b>Cardano V11 Hard Fork schreitet voran, da Discord-Konflikt \u00c4ngste vor Governance sch\u00fcrt<\/b><\/a><\/p>\n<h2><b>Cardano-Entwicklung und -Veranstaltungen gehen weiter<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Santiment Intelligence wies auch auf aktive Arbeit innerhalb der Organisation hin<\/span><a href=\"https:\/\/www.livebitcoinnews.com\/cardano-defies-ecosystem-drama-as-ada-surges-11-in-one-week\/\"><span style=\"font-weight: 400\">Cardano-\u00d6kosystem<\/span><\/a><span style=\"font-weight: 400\">. Zu diesen Bereichen geh\u00f6ren die Leios-Testnetzarbeit, Hydra-Skalierungs-Upgrades und Mithril-Fortschritte. Es wurden auch Pyth-Orakel und neue \u00d6kosystemfinanzierungsaktivit\u00e4ten erw\u00e4hnt.<\/span><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Wir best\u00e4tigen, dass unsere Teams die Verantwortung f\u00fcr Token2049 \u00fcbernehmen und haben zugestimmt, den Cardano-Stand auf der Token2049 zu liefern, wie von DReps abgestimmt und in den Metadaten der Governance-Ma\u00dfnahmen beschrieben.<\/p>\n<p>Zus\u00e4tzlich zum Cardano-Stand organisieren wir auch das Side-Event\u2026<a href=\"https:\/\/t.co\/UlNcqlUcqU\">https:\/\/t.co\/UlNcqlUcqU<\/a><\/p>\n<p>\u2014 Cardano Foundation (@Cardano_CF)<a href=\"https:\/\/x.com\/Cardano_CF\/status\/2076960599930523921?ref_src=twsrc%5Etfw\">14. Juli 2026<\/a><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400\">Die Cardano Foundation best\u00e4tigte, dass sie den Cardano-Stand auf der Token2049 bereitstellen wird. Die Entscheidung folgt einer Governance-Ma\u00dfnahme, \u00fcber die DReps abgestimmt hat. DReps sind Vertreter, die am Governance-Prozess von Cardano beteiligt sind.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die Stiftung organisiert au\u00dferdem die CardanoxDraperxBitcoin-Nebenveranstaltung in Singapur. Die Veranstaltung wird von Draper und der Cardano Foundation finanziert. Weitere Details werden erwartet, wenn sich der Token2049-Zeitplan \u00e4ndert<\/span>n\u00e4her.<\/p>\n<p><!-- source_url: https:\/\/www.livebitcoinnews.com\/cardano-whales-hit-3-5-year-high-as-retail-dumps-ada\/ --><\/p>\n<p><em>Quelle: <a href=\"https:\/\/www.livebitcoinnews.com\/cardano-whales-hit-3-5-year-high-as-retail-dumps-ada\/\" rel=\"nofollow noopener\" target=\"_blank\">Live Bitcoin News<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cardano-Wallets mit 100.000 bis 100 Mio. ADA-Top-25,6-Milliarden-M\u00fcnzen, der h\u00f6chste Wert seit Februar 2023, da Sub-100-ADA-Wallets um 0,7 % fielen. Die gr\u00f6\u00dferen Inhaber von Cardano haben ihren Betrag erh\u00f6htADA-Guthabenauf ein 3,5-Jahres-Hoch. Der Schritt erfolgt, da Einzelhandels-Wallets das Risiko verringern. Santiment Intelligence sagte, dass Wallets mit 100.000 bis 100 Millionen ADA mittlerweile mehr als 25,6 Milliarden M\u00fcnzen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[142],"tags":[],"class_list":["post-8999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cardano"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft - German Live Bitcoin News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft - German Live Bitcoin News\" \/>\n<meta property=\"og:description\" content=\"Cardano-Wallets mit 100.000 bis 100 Mio. ADA-Top-25,6-Milliarden-M\u00fcnzen, der h\u00f6chste Wert seit Februar 2023, da Sub-100-ADA-Wallets um 0,7 % fielen. Die gr\u00f6\u00dferen Inhaber von Cardano haben ihren Betrag erh\u00f6htADA-Guthabenauf ein 3,5-Jahres-Hoch. Der Schritt erfolgt, da Einzelhandels-Wallets das Risiko verringern. Santiment Intelligence sagte, dass Wallets mit 100.000 bis 100 Millionen ADA mittlerweile mehr als 25,6 Milliarden M\u00fcnzen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/\" \/>\n<meta property=\"og:site_name\" content=\"German Live Bitcoin News\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T12:01:12+00:00\" \/>\n<meta name=\"author\" content=\"germanlbn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"germanlbn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/\"},\"author\":{\"name\":\"germanlbn\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\"},\"headline\":\"Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft\",\"datePublished\":\"2026-07-14T12:01:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/\"},\"wordCount\":583,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/pikaso_reimagine_A-closeup-of-several-gold-Cardano-ADA-cryptocurren-scaled-2.jpg\",\"articleSection\":[\"Cardano\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/\",\"name\":\"Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft - German Live Bitcoin News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/pikaso_reimagine_A-closeup-of-several-gold-Cardano-ADA-cryptocurren-scaled-2.jpg\",\"datePublished\":\"2026-07-14T12:01:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/#primaryimage\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/pikaso_reimagine_A-closeup-of-several-gold-Cardano-ADA-cryptocurren-scaled-2.jpg\",\"contentUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/pikaso_reimagine_A-closeup-of-several-gold-Cardano-ADA-cryptocurren-scaled-2.jpg\",\"width\":2560,\"height\":1463},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#website\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/\",\"name\":\"German Live Bitcoin News\",\"description\":\"Live Bitcoin News ist die Quelle f\u00fcr aktuelle Nachrichten zu Ethereum, XRP, DeFi, Web 3.0, Kryptotrends, Marktanalysen, Blockchain und globalen Finanznachrichten \u2013 24 Stunden am Tag, 7 Tage die Woche.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\",\"name\":\"germanlbn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"caption\":\"germanlbn\"},\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/author\\\/germanlbn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft - German Live Bitcoin News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/","og_locale":"de_DE","og_type":"article","og_title":"Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft - German Live Bitcoin News","og_description":"Cardano-Wallets mit 100.000 bis 100 Mio. ADA-Top-25,6-Milliarden-M\u00fcnzen, der h\u00f6chste Wert seit Februar 2023, da Sub-100-ADA-Wallets um 0,7 % fielen. Die gr\u00f6\u00dferen Inhaber von Cardano haben ihren Betrag erh\u00f6htADA-Guthabenauf ein 3,5-Jahres-Hoch. Der Schritt erfolgt, da Einzelhandels-Wallets das Risiko verringern. Santiment Intelligence sagte, dass Wallets mit 100.000 bis 100 Millionen ADA mittlerweile mehr als 25,6 Milliarden M\u00fcnzen [&hellip;]","og_url":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/","og_site_name":"German Live Bitcoin News","article_published_time":"2026-07-14T12:01:12+00:00","author":"germanlbn","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"germanlbn","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/#article","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/"},"author":{"name":"germanlbn","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a"},"headline":"Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft","datePublished":"2026-07-14T12:01:12+00:00","mainEntityOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/"},"wordCount":583,"commentCount":0,"image":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/pikaso_reimagine_A-closeup-of-several-gold-Cardano-ADA-cryptocurren-scaled-2.jpg","articleSection":["Cardano"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/","url":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/","name":"Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft - German Live Bitcoin News","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/#website"},"primaryImageOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/#primaryimage"},"image":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/pikaso_reimagine_A-closeup-of-several-gold-Cardano-ADA-cryptocurren-scaled-2.jpg","datePublished":"2026-07-14T12:01:12+00:00","author":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a"},"breadcrumb":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/#primaryimage","url":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/pikaso_reimagine_A-closeup-of-several-gold-Cardano-ADA-cryptocurren-scaled-2.jpg","contentUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/pikaso_reimagine_A-closeup-of-several-gold-Cardano-ADA-cryptocurren-scaled-2.jpg","width":2560,"height":1463},{"@type":"BreadcrumbList","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/cardano-whales-erreichen-35-jahres-hoch-da-der-einzelhandel-ada-abstoesst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/global.livebitcoinnews.com\/ge\/"},{"@type":"ListItem","position":2,"name":"Cardano Whales erreichen 3,5-Jahres-Hoch, da der Einzelhandel ADA abst\u00f6\u00dft"}]},{"@type":"WebSite","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#website","url":"https:\/\/global.livebitcoinnews.com\/ge\/","name":"German Live Bitcoin News","description":"Live Bitcoin News ist die Quelle f\u00fcr aktuelle Nachrichten zu Ethereum, XRP, DeFi, Web 3.0, Kryptotrends, Marktanalysen, Blockchain und globalen Finanznachrichten \u2013 24 Stunden am Tag, 7 Tage die Woche.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/global.livebitcoinnews.com\/ge\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a","name":"germanlbn","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","caption":"germanlbn"},"url":"https:\/\/global.livebitcoinnews.com\/ge\/author\/germanlbn\/"}]}},"_links":{"self":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts\/8999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/comments?post=8999"}],"version-history":[{"count":0,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts\/8999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/media\/8998"}],"wp:attachment":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/media?parent=8999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/categories?post=8999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/tags?post=8999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}