{"id":9044,"date":"2026-07-14T18:01:35","date_gmt":"2026-07-14T18:01:35","guid":{"rendered":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/"},"modified":"2026-07-14T18:01:35","modified_gmt":"2026-07-14T18:01:35","slug":"ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert","status":"publish","type":"post","link":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/","title":{"rendered":"Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert"},"content":{"rendered":"<ul>\n<li style=\"font-weight: 400\"><em><span style=\"font-weight: 400\">Der ehemalige LASD-Abgeordnete Scott Simpkins gab zu, w\u00e4hrend einer Bundesermittlung gegen Adam Iza gelogen zu haben.<\/span><\/em><\/li>\n<li style=\"font-weight: 400\"><em><span style=\"font-weight: 400\">Die Staatsanw\u00e4lte brachten Simpkins mit einem Vorfall im Jahr 2021 in Verbindung, bei dem es um eine angebliche Erpressungsforderung in H\u00f6he von 25.000 US-Dollar ging.<\/span><\/em><\/li>\n<li style=\"font-weight: 400\"><em><span style=\"font-weight: 400\">Adam Iza sieht sich mit mehreren Bundesverfahren konfrontiert, in denen es um Betrug, Raub und Verbrechen im Zusammenhang mit Kryptow\u00e4hrungen geht.<\/span><\/em><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Ein ehemaliger Stellvertreter des Sheriff-Departments des Los Angeles County wurde zu 18 Monaten Bundesgef\u00e4ngnis verurteilt, nachdem er zugegeben hatte, dass er eine bundesstaatliche Untersuchung gegen den Kryptow\u00e4hrungsunternehmer Adam Iza behindert habe.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Scott Allen Simpkins wurde beschuldigt, die Ermittler belogen zu haben, weil er gesehen hatte, wie Iza w\u00e4hrend eines Vorfalls in einem Herrenhaus in Bel Air im Jahr 2021 ein Opfer bedrohte und eine Zahlung in H\u00f6he von 25.000 US-Dollar forderte.<\/span><\/p>\n<h2><b>Simpkins gab zu, \u00fcber den Erpressungsvorfall von 2021 gelogen zu haben<\/b><\/h2>\n<p><span style=\"font-weight: 400\">\u00a0In einem<\/span><a href=\"https:\/\/www.justice.gov\/usao-cdca\/pr\/former-la-county-sheriffs-deputy-sentenced-18-months-federal-prison-obstructing\"><span style=\"font-weight: 400\">Stellungnahme<\/span><\/a><span style=\"font-weight: 400\">Am Montag verurteilte der US-Bezirksrichter Percy Anderson Simpkins und verh\u00e4ngte eine Geldstrafe von 10.000 US-Dollar, nachdem sich der ehemalige Stellvertreter der Behinderung der Justiz schuldig bekannt hatte. Simpkins trat nach seinem Pl\u00e4doyer f\u00fcr ein Verbrechen aus dem LASD Special Enforcement Bureau zur\u00fcck.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nach Angaben der US-Staatsanwaltschaft f\u00fcr den Central District of California arbeitete Simpkins als Stellvertreter der LASD Lakewood Station und diente sp\u00e4ter beim Special Enforcement Bureau und dem SWAT-Team der Abteilung. \u00dcber Saavedra &amp; Associates erbrachte er auch private Sicherheitsdienste.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Staatsanw\u00e4lte sagten, Simpkins geh\u00f6rte zu mehreren Polizeibeamten, die w\u00e4hrend einer privaten Party im August 2021 angeheuert wurden, um f\u00fcr die Sicherheit in Izas Bel Air-Residenz zu sorgen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Das Unternehmen geh\u00f6rte dem damaligen LASD-Abgeordneten Eric Chase Saavedra und besch\u00e4ftigte aktives Strafverfolgungspersonal f\u00fcr private Sicherheitsauftr\u00e4ge.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nach der Party sagten Staatsanw\u00e4lte, Partyplaner R.C. wurde aufgrund von Vorw\u00fcrfen des st\u00f6renden Verhaltens von der Veranstaltung ausgeschlossen. Am folgenden Tag begleiteten Simpkins und der ehemalige Stellvertreter Christopher Michael Cadman R.C. in Izas B\u00fcro in seiner Wohnung.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die Bundesbeh\u00f6rden behaupteten, Iza habe versucht, R.C. einzusch\u00fcchtern. w\u00e4hrend des Treffens, indem er mehrere scharfe 9-mm-Patronen auf seinen Schreibtisch legte. Die Staatsanwaltschaft gab an, dass Iza sp\u00e4ter eine \u00dcberweisung von 25.000 US-Dollar von R.C.s Bankkonto auf ein von ihm kontrolliertes Konto verlangt habe.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Laut Gerichtsdokumenten begleiteten Simpkins und Cadman R.C. von der Immobilie, nachdem die Zahlung abgeschlossen wurde. Die Staatsanw\u00e4lte sagten, beide Stellvertreter h\u00e4tten sp\u00e4ter finanziell profitiert, nachdem sie Saavedra &amp; Associates dabei geholfen hatten, eine fortgesetzte Sicherheitsvereinbarung mit Iza abzuschlie\u00dfen.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Simpkins und Cadman erhielten jeweils etwa 1.400 US-Dollar f\u00fcr ihre Arbeit w\u00e4hrend der Party und des Vorfalls vom 16. August. Nach Angaben der Staatsanwaltschaft erhielten sie au\u00dferdem etwa 10 % des ersten Monatsgewinns des Unternehmens aus dem Sicherheitsvertrag.<\/span><\/p>\n<h2><b>Adam Iza bleibt in mehrere Bundesf\u00e4lle verwickelt<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Der Fall ist Teil umfassenderer Bundesermittlungen gegen Adam Iza, der sich selbst als Kryptow\u00e4hrungsunternehmer bezeichnete und den Spitznamen \u201eDer Pate\u201c verwendete. Iza befindet sich seit September 2024 in Bundesgewahrsam, nachdem ihn die Beh\u00f6rden wegen mehrerer mutma\u00dflicher Verbrechen festgenommen hatten.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Im Januar 2025 bekannte sich Iza der Verschw\u00f6rung gegen Rechte schuldig, berichtete Wire<\/span><a href=\"https:\/\/www.livebitcoinnews.com\/do-kwon-may-plead-guilty-in-u-s-fraud-case-linked-to-terrausd-collapse\/\"><span style=\"font-weight: 400\">Betrug<\/span><\/a><span style=\"font-weight: 400\">und Steuerhinterziehungsvorw\u00fcrfe in Kalifornien. Er wartet in diesem Fall auf die Verurteilung.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Dar\u00fcber hinaus Iza<\/span><a href=\"https:\/\/www.justice.gov\/usao-ct\/pr\/california-man-admits-role-attempted-robbery-danbury\"><span style=\"font-weight: 400\">bekannte sich schuldig<\/span><\/a><span style=\"font-weight: 400\">im Juni 2026 im Bezirk Connecticut wegen Verschw\u00f6rung zur Beeintr\u00e4chtigung des Handels durch Raub. Die Anklage bezieht sich auf einen mutma\u00dflichen Bitcoin-bezogenen Entf\u00fchrungs- und Raub\u00fcberfall in Danbury, Connecticut, im August 2024.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die Bundesanwaltschaft sagte, dass es sich bei dem Fall Connecticut um einen Versuch handelte, Kryptow\u00e4hrungen zu erhalten, die mit einem Streit \u00fcber gestohlene Bitcoins in Zusammenhang standen. Die Ermittlungen f\u00fchrten auch zu Schuldgest\u00e4ndnissen anderer Personen, darunter ehemaliger Polizeibeamter.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Der ehemalige LASD-Abgeordnete Michael David Coberg verb\u00fc\u00dft \u200b\u200bdanach eine 63-monatige Bundesgef\u00e4ngnisstrafe<\/span><a href=\"https:\/\/www.livebitcoinnews.com\/bitcoin-ponzi-ceo-pleads-guilty-promised-3-daily-returns\/\"><span style=\"font-weight: 400\">sich schuldig bekennen<\/span><\/a><span style=\"font-weight: 400\">Iza dabei zu helfen, eine Person zu erpressen und eine betr\u00fcgerische Verhaftungsaktion zu arrangieren. Au\u00dferdem wurde er zur Zahlung einer Entsch\u00e4digung in H\u00f6he von 127.000 US-Dollar verurteilt.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Das FBI und das IRS Criminal Investigation leiteten die Ermittlungen in dem Fall, w\u00e4hrend das Los Angeles County Sheriff\u2019s Department die Bundesbeh\u00f6rden w\u00e4hrend des gesamten Verfahrens unterst\u00fctzte.<\/span><\/p>\n<p><!-- source_url: https:\/\/www.livebitcoinnews.com\/former-la-deputy-jailed-for-obstructing-crypto-mogul-extortion-probe\/ --><\/p>\n<p><em>Quelle: <a href=\"https:\/\/www.livebitcoinnews.com\/former-la-deputy-jailed-for-obstructing-crypto-mogul-extortion-probe\/\" rel=\"nofollow noopener\" target=\"_blank\">Live Bitcoin News<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der ehemalige LASD-Abgeordnete Scott Simpkins gab zu, w\u00e4hrend einer Bundesermittlung gegen Adam Iza gelogen zu haben. Die Staatsanw\u00e4lte brachten Simpkins mit einem Vorfall im Jahr 2021 in Verbindung, bei dem es um eine angebliche Erpressungsforderung in H\u00f6he von 25.000 US-Dollar ging. Adam Iza sieht sich mit mehreren Bundesverfahren konfrontiert, in denen es um Betrug, Raub [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[151],"tags":[1359,1360,1361,1362],"class_list":["post-9044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-crime","tag-fbi-investigation","tag-adam-iza","tag-cryptocurrency-crime","tag-scott-simpkins"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert - German Live Bitcoin News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert - German Live Bitcoin News\" \/>\n<meta property=\"og:description\" content=\"Der ehemalige LASD-Abgeordnete Scott Simpkins gab zu, w\u00e4hrend einer Bundesermittlung gegen Adam Iza gelogen zu haben. Die Staatsanw\u00e4lte brachten Simpkins mit einem Vorfall im Jahr 2021 in Verbindung, bei dem es um eine angebliche Erpressungsforderung in H\u00f6he von 25.000 US-Dollar ging. Adam Iza sieht sich mit mehreren Bundesverfahren konfrontiert, in denen es um Betrug, Raub [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/\" \/>\n<meta property=\"og:site_name\" content=\"German Live Bitcoin News\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T18:01:35+00:00\" \/>\n<meta name=\"author\" content=\"germanlbn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"germanlbn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/\"},\"author\":{\"name\":\"germanlbn\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\"},\"headline\":\"Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert\",\"datePublished\":\"2026-07-14T18:01:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/\"},\"wordCount\":706,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/FBI-recovers-funds-for-victims-of-scammed-banker-01-1.png\",\"keywords\":[\"#FBI investigation\",\"Adam Iza\",\"Cryptocurrency Crime\",\"Scott Simpkins\"],\"articleSection\":[\"Crime\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/\",\"name\":\"Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert - German Live Bitcoin News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/FBI-recovers-funds-for-victims-of-scammed-banker-01-1.png\",\"datePublished\":\"2026-07-14T18:01:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/FBI-recovers-funds-for-victims-of-scammed-banker-01-1.png\",\"contentUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/FBI-recovers-funds-for-victims-of-scammed-banker-01-1.png\",\"width\":1472,\"height\":816},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#website\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/\",\"name\":\"German Live Bitcoin News\",\"description\":\"Live Bitcoin News ist die Quelle f\u00fcr aktuelle Nachrichten zu Ethereum, XRP, DeFi, Web 3.0, Kryptotrends, Marktanalysen, Blockchain und globalen Finanznachrichten \u2013 24 Stunden am Tag, 7 Tage die Woche.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\",\"name\":\"germanlbn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"caption\":\"germanlbn\"},\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/author\\\/germanlbn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert - German Live Bitcoin News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/","og_locale":"de_DE","og_type":"article","og_title":"Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert - German Live Bitcoin News","og_description":"Der ehemalige LASD-Abgeordnete Scott Simpkins gab zu, w\u00e4hrend einer Bundesermittlung gegen Adam Iza gelogen zu haben. Die Staatsanw\u00e4lte brachten Simpkins mit einem Vorfall im Jahr 2021 in Verbindung, bei dem es um eine angebliche Erpressungsforderung in H\u00f6he von 25.000 US-Dollar ging. Adam Iza sieht sich mit mehreren Bundesverfahren konfrontiert, in denen es um Betrug, Raub [&hellip;]","og_url":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/","og_site_name":"German Live Bitcoin News","article_published_time":"2026-07-14T18:01:35+00:00","author":"germanlbn","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"germanlbn","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/#article","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/"},"author":{"name":"germanlbn","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a"},"headline":"Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert","datePublished":"2026-07-14T18:01:35+00:00","mainEntityOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/"},"wordCount":706,"commentCount":0,"image":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/FBI-recovers-funds-for-victims-of-scammed-banker-01-1.png","keywords":["#FBI investigation","Adam Iza","Cryptocurrency Crime","Scott Simpkins"],"articleSection":["Crime"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/","url":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/","name":"Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert - German Live Bitcoin News","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/#website"},"primaryImageOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/#primaryimage"},"image":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/FBI-recovers-funds-for-victims-of-scammed-banker-01-1.png","datePublished":"2026-07-14T18:01:35+00:00","author":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a"},"breadcrumb":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/#primaryimage","url":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/FBI-recovers-funds-for-victims-of-scammed-banker-01-1.png","contentUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/FBI-recovers-funds-for-victims-of-scammed-banker-01-1.png","width":1472,"height":816},{"@type":"BreadcrumbList","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ehemaliger-la-abgeordneter-wegen-behinderung-der-erpressungsermittlung-des-crypto-moguls-inhaftiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/global.livebitcoinnews.com\/ge\/"},{"@type":"ListItem","position":2,"name":"Ehemaliger LA-Abgeordneter wegen Behinderung der Erpressungsermittlung des Crypto-Moguls inhaftiert"}]},{"@type":"WebSite","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#website","url":"https:\/\/global.livebitcoinnews.com\/ge\/","name":"German Live Bitcoin News","description":"Live Bitcoin News ist die Quelle f\u00fcr aktuelle Nachrichten zu Ethereum, XRP, DeFi, Web 3.0, Kryptotrends, Marktanalysen, Blockchain und globalen Finanznachrichten \u2013 24 Stunden am Tag, 7 Tage die Woche.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/global.livebitcoinnews.com\/ge\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a","name":"germanlbn","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","caption":"germanlbn"},"url":"https:\/\/global.livebitcoinnews.com\/ge\/author\/germanlbn\/"}]}},"_links":{"self":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts\/9044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/comments?post=9044"}],"version-history":[{"count":0,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts\/9044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/media\/9043"}],"wp:attachment":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/media?parent=9044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/categories?post=9044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/tags?post=9044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}