{"id":9050,"date":"2026-07-14T19:01:01","date_gmt":"2026-07-14T19:01:01","guid":{"rendered":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/"},"modified":"2026-07-14T19:01:01","modified_gmt":"2026-07-14T19:01:01","slug":"ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus","status":"publish","type":"post","link":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/","title":{"rendered":"EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus"},"content":{"rendered":"<ul>\n<li style=\"font-weight: 400\"><em><span style=\"font-weight: 400\">Die EZB w\u00e4hlt 36 Anbieter aus, um Funktionen, Abl\u00e4ufe und Zahlungssysteme des digitalen Euro zu testen.<\/span><\/em><\/li>\n<li style=\"font-weight: 400\"><em><span style=\"font-weight: 400\">Das Pilotprojekt wird Online-, Offline-, Mobil- und H\u00e4ndlerzahlungsm\u00f6glichkeiten in ganz Europa bewerten.<\/span><\/em><\/li>\n<li style=\"font-weight: 400\"><em><span style=\"font-weight: 400\">Die Ergebnisse werden die Entwicklung des digitalen Euro vor einer m\u00f6glichen Ausgabeentscheidung im Jahr 2029 leiten.<\/span><\/em><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Die Europ\u00e4ische Zentralbank hat 36 Zahlungsdienstleister f\u00fcr die Teilnahme an einem 12-monatigen Pilotprojekt zum digitalen Euro ausgew\u00e4hlt, das in der zweiten H\u00e4lfte des Jahres 2027 beginnen soll. Dies stellt einen wichtigen Schritt in den Vorbereitungen der europ\u00e4ischen Zentralbank f\u00fcr digitale W\u00e4hrungen dar.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die ausgew\u00e4hlten Unternehmen werden dabei helfen, Zahlungsfunktionen, betriebliche Prozesse und Benutzererfahrungen zu testen, w\u00e4hrend die EZB die m\u00f6gliche zuk\u00fcnftige Einf\u00fchrung eines digitalen Euro im gesamten Euroraum bewertet.<\/span><\/p>\n<h2><b>EZB weitet digitale Euro-Tests mit Unterst\u00fctzung der Zahlungsverkehrsbranche aus<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Laut offizieller Pressemitteilung hat die EZB<\/span><a href=\"https:\/\/www.ecb.europa.eu\/press\/pr\/date\/2026\/html\/ecb.pr260714~8cd07d9d45.en.html\"><span style=\"font-weight: 400\">ausgew\u00e4hlt<\/span><\/a><span style=\"font-weight: 400\">die 36 Anbieter aus mehr als 50 Bewerbungen, die nach einem Aufruf zur Interessenbekundung im M\u00e4rz 2026 eingereicht wurden. Zu den Teilnehmern geh\u00f6ren Banken und Nichtbank-Zahlungsunternehmen mit unterschiedlichen Gesch\u00e4ftsmodellen und regionaler Abdeckung.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Zu den ausgew\u00e4hlten Teilnehmern z\u00e4hlen gro\u00dfe Finanzinstitute, darunter die Deutsche Bank, UniCredit, Revolut, Stripe und Adyen.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die EZB sagte, die breite Auswahl w\u00fcrde eine vielf\u00e4ltige Testumgebung schaffen und es der Zentralbank gleichzeitig erm\u00f6glichen, zu beurteilen, wie verschiedene Anbieter digitale Euro-Dienste unterst\u00fctzen.<\/span><\/p>\n<p><span style=\"font-weight: 400\">EZB-Direktoriumsmitglied Piero Cipollone stellte fest, dass die starke Marktbeteiligung die Bereitschaft des privaten Sektors widerspiegelt, die Entwicklung eines sicheren und effizienten europ\u00e4ischen Zahlungs\u00f6kosystems zu unterst\u00fctzen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Beim Pilotprojekt wird eine Beta-Version des digitalen Euro zum Einsatz kommen, die dem geplanten technischen Design weitgehend entspricht, w\u00e4hrend der Testphase jedoch keinen Status als gesetzliches Zahlungsmittel haben wird.<\/span><\/p>\n<h2><b>Das Pilotprojekt wird Online-, Offline- und H\u00e4ndlerzahlungen testen<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Am digitalen Euro-Pilotprojekt wird beteiligt sein<\/span><a href=\"https:\/\/www.livebitcoinnews.com\/ecb-plans-blockchain-settlement-in-central-bank-money-next-year\/\"><span style=\"font-weight: 400\">EZB<\/span><\/a><span style=\"font-weight: 400\">und 19 nationale Zentralbanken im gesamten Euroraum.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Dar\u00fcber hinaus nehmen ausgew\u00e4hlte H\u00e4ndler und Zentralbankmitarbeiter an praktischen Zahlungsversuchen teil.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Das Testprogramm wird mehrere Zahlungsszenarien untersuchen, darunter \u00dcberweisungen von Person zu Person und Transaktionen von Person zu Unternehmen. Dar\u00fcber hinaus testen die Teilnehmer Online-Zahlungen, Offline-\u00dcberweisungen, mobile Zahlungen und Point-of-Sale-Transaktionen.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ausgew\u00e4hlte Anbieter werden w\u00e4hrend des Pilotprojekts in unterschiedlichen Rollen agieren. Vertreibende Zahlungsanbieter werden Benutzern den Zugang zu digitalen Beta-Euro-Konten erleichtern, w\u00e4hrend Acquiring-Anbieter es H\u00e4ndlern erm\u00f6glichen werden, digitale Euro-Zahlungen zu akzeptieren.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Einige Unternehmen \u00fcbernehmen beide Rollen, sodass die EZB mehrere Betriebsmodelle innerhalb derselben Testumgebung bewerten kann.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die Zentralbank sagte, dass teilnehmende Anbieter je nach Struktur des Programms und betrieblichen Anforderungen Pilotdienste au\u00dferhalb ihrer Heimatl\u00e4nder unterst\u00fctzen k\u00f6nnten.<\/span><\/p>\n<h2><b>Die digitale Euro-Roadmap schreitet in Richtung einer m\u00f6glichen Einf\u00fchrung im Jahr 2029 voran<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Das Pilotprojekt stellt einen weiteren Meilenstein in der Vorbereitungsphase der EZB f\u00fcr eine m\u00f6gliche Ausgabe eines digitalen Euro dar. Allerdings hat die Zentralbank betont, dass eine endg\u00fcltige Startentscheidung von der Zustimmung der notwendigen europ\u00e4ischen Gesetzgebung abh\u00e4ngt.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die EZB strebt derzeit die Bereitschaft f\u00fcr eine m\u00f6gliche erste Emission im Jahr 2029 an, allerdings muss der Gesetzgeber den rechtlichen Rahmen festlegen, bevor die Umsetzung erfolgen kann.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Der<\/span><a href=\"https:\/\/www.livebitcoinnews.com\/ecb-locks-in-european-standards-to-power-digital-euro-payments\/\"><span style=\"font-weight: 400\">digitaler Euro<\/span><\/a><span style=\"font-weight: 400\">Ziel der Initiative ist es, die europ\u00e4ische Zahlungsinfrastruktur zu st\u00e4rken und gleichzeitig die Abh\u00e4ngigkeit von externen Zahlungsnetzwerken zu verringern. Dar\u00fcber hinaus haben Beamte argumentiert, dass das Projekt eine gr\u00f6\u00dfere strategische Unabh\u00e4ngigkeit im digitalen Zahlungsverkehr unterst\u00fctzen k\u00f6nnte.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Im Anschluss an das Pilotprojekt wird die EZB die Ergebnisse analysieren und das technische Design, die Sicherheitsfunktionen und die Benutzererfahrung des digitalen Euro verfeinern, bevor sie weitere Entscheidungen trifft.<\/span><\/p>\n<p><!-- source_url: https:\/\/www.livebitcoinnews.com\/ecb-selects-36-payment-firms-for-major-digital-euro-pilot-launch\/ --><\/p>\n<p><em>Quelle: <a href=\"https:\/\/www.livebitcoinnews.com\/ecb-selects-36-payment-firms-for-major-digital-euro-pilot-launch\/\" rel=\"nofollow noopener\" target=\"_blank\">Live Bitcoin News<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die EZB w\u00e4hlt 36 Anbieter aus, um Funktionen, Abl\u00e4ufe und Zahlungssysteme des digitalen Euro zu testen. Das Pilotprojekt wird Online-, Offline-, Mobil- und H\u00e4ndlerzahlungsm\u00f6glichkeiten in ganz Europa bewerten. Die Ergebnisse werden die Entwicklung des digitalen Euro vor einer m\u00f6glichen Ausgabeentscheidung im Jahr 2029 leiten. Die Europ\u00e4ische Zentralbank hat 36 Zahlungsdienstleister f\u00fcr die Teilnahme an einem [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1148,8],"tags":[200,1177,1178],"class_list":["post-9050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cbdc","category-market-news","tag-cbdc","tag-digital-euro","tag-ecb"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus - German Live Bitcoin News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus - German Live Bitcoin News\" \/>\n<meta property=\"og:description\" content=\"Die EZB w\u00e4hlt 36 Anbieter aus, um Funktionen, Abl\u00e4ufe und Zahlungssysteme des digitalen Euro zu testen. Das Pilotprojekt wird Online-, Offline-, Mobil- und H\u00e4ndlerzahlungsm\u00f6glichkeiten in ganz Europa bewerten. Die Ergebnisse werden die Entwicklung des digitalen Euro vor einer m\u00f6glichen Ausgabeentscheidung im Jahr 2029 leiten. Die Europ\u00e4ische Zentralbank hat 36 Zahlungsdienstleister f\u00fcr die Teilnahme an einem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/\" \/>\n<meta property=\"og:site_name\" content=\"German Live Bitcoin News\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T19:01:01+00:00\" \/>\n<meta name=\"author\" content=\"germanlbn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"germanlbn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/\"},\"author\":{\"name\":\"germanlbn\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\"},\"headline\":\"EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus\",\"datePublished\":\"2026-07-14T19:01:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/\"},\"wordCount\":601,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Nine_Major_European_Banks_Unite_to_Launch_MiCA_Compliant_Euro_Stablecoin-6-1.png\",\"keywords\":[\"CBDC\",\"digital Euro\",\"ECB\"],\"articleSection\":[\"CBDC\",\"Market News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/\",\"name\":\"EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus - German Live Bitcoin News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Nine_Major_European_Banks_Unite_to_Launch_MiCA_Compliant_Euro_Stablecoin-6-1.png\",\"datePublished\":\"2026-07-14T19:01:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Nine_Major_European_Banks_Unite_to_Launch_MiCA_Compliant_Euro_Stablecoin-6-1.png\",\"contentUrl\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Nine_Major_European_Banks_Unite_to_Launch_MiCA_Compliant_Euro_Stablecoin-6-1.png\",\"width\":1216,\"height\":832},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/2026\\\/07\\\/14\\\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#website\",\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/\",\"name\":\"German Live Bitcoin News\",\"description\":\"Live Bitcoin News ist die Quelle f\u00fcr aktuelle Nachrichten zu Ethereum, XRP, DeFi, Web 3.0, Kryptotrends, Marktanalysen, Blockchain und globalen Finanznachrichten \u2013 24 Stunden am Tag, 7 Tage die Woche.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/#\\\/schema\\\/person\\\/41f362c99de6879e21134a1b2b554c1a\",\"name\":\"germanlbn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g\",\"caption\":\"germanlbn\"},\"url\":\"https:\\\/\\\/global.livebitcoinnews.com\\\/ge\\\/author\\\/germanlbn\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus - German Live Bitcoin News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/","og_locale":"de_DE","og_type":"article","og_title":"EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus - German Live Bitcoin News","og_description":"Die EZB w\u00e4hlt 36 Anbieter aus, um Funktionen, Abl\u00e4ufe und Zahlungssysteme des digitalen Euro zu testen. Das Pilotprojekt wird Online-, Offline-, Mobil- und H\u00e4ndlerzahlungsm\u00f6glichkeiten in ganz Europa bewerten. Die Ergebnisse werden die Entwicklung des digitalen Euro vor einer m\u00f6glichen Ausgabeentscheidung im Jahr 2029 leiten. Die Europ\u00e4ische Zentralbank hat 36 Zahlungsdienstleister f\u00fcr die Teilnahme an einem [&hellip;]","og_url":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/","og_site_name":"German Live Bitcoin News","article_published_time":"2026-07-14T19:01:01+00:00","author":"germanlbn","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"germanlbn","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/#article","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/"},"author":{"name":"germanlbn","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a"},"headline":"EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus","datePublished":"2026-07-14T19:01:01+00:00","mainEntityOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/"},"wordCount":601,"commentCount":0,"image":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/Nine_Major_European_Banks_Unite_to_Launch_MiCA_Compliant_Euro_Stablecoin-6-1.png","keywords":["CBDC","digital Euro","ECB"],"articleSection":["CBDC","Market News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/","url":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/","name":"EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus - German Live Bitcoin News","isPartOf":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/#website"},"primaryImageOfPage":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/#primaryimage"},"image":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/Nine_Major_European_Banks_Unite_to_Launch_MiCA_Compliant_Euro_Stablecoin-6-1.png","datePublished":"2026-07-14T19:01:01+00:00","author":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a"},"breadcrumb":{"@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/#primaryimage","url":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/Nine_Major_European_Banks_Unite_to_Launch_MiCA_Compliant_Euro_Stablecoin-6-1.png","contentUrl":"https:\/\/global.livebitcoinnews.com\/ge\/wp-content\/uploads\/sites\/5\/2026\/07\/Nine_Major_European_Banks_Unite_to_Launch_MiCA_Compliant_Euro_Stablecoin-6-1.png","width":1216,"height":832},{"@type":"BreadcrumbList","@id":"https:\/\/global.livebitcoinnews.com\/ge\/2026\/07\/14\/ezb-waehlt-36-zahlungsunternehmen-fuer-den-start-eines-grossen-digitalen-euro-pilotprojekts-aus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/global.livebitcoinnews.com\/ge\/"},{"@type":"ListItem","position":2,"name":"EZB w\u00e4hlt 36 Zahlungsunternehmen f\u00fcr den Start eines gro\u00dfen digitalen Euro-Pilotprojekts aus"}]},{"@type":"WebSite","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#website","url":"https:\/\/global.livebitcoinnews.com\/ge\/","name":"German Live Bitcoin News","description":"Live Bitcoin News ist die Quelle f\u00fcr aktuelle Nachrichten zu Ethereum, XRP, DeFi, Web 3.0, Kryptotrends, Marktanalysen, Blockchain und globalen Finanznachrichten \u2013 24 Stunden am Tag, 7 Tage die Woche.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/global.livebitcoinnews.com\/ge\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/global.livebitcoinnews.com\/ge\/#\/schema\/person\/41f362c99de6879e21134a1b2b554c1a","name":"germanlbn","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fba58a7a0f25f48c7b91e5bd945cd723d6f1d6b622b31a5184dc56efd71b4024?s=96&d=mm&r=g","caption":"germanlbn"},"url":"https:\/\/global.livebitcoinnews.com\/ge\/author\/germanlbn\/"}]}},"_links":{"self":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts\/9050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/comments?post=9050"}],"version-history":[{"count":0,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/posts\/9050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/media\/9049"}],"wp:attachment":[{"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/media?parent=9050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/categories?post=9050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/global.livebitcoinnews.com\/ge\/wp-json\/wp\/v2\/tags?post=9050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}